{"id":1069,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/ru\/tag\/exterior-netting\/","name":"exterior netting","slug":"exterior-netting","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/ru\/wp-json\/wp\/v2\/tags\/1069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/ru\/wp-json\/wp\/v2\/posts?tags=1069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}