{"id":1022,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/ko\/tag\/sports-facility-netting-expense\/","name":"sports facility netting expense","slug":"sports-facility-netting-expense","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/ko\/wp-json\/wp\/v2\/tags\/1022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/ko\/wp-json\/wp\/v2\/posts?tags=1022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}