{"id":706,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/ja\/tag\/uv-stabilized-mesh-netting\/","name":"UV\u5b89\u5b9a\u5316\u30e1\u30c3\u30b7\u30e5\u30cd\u30c3\u30c8","slug":"uv-stabilized-mesh-netting","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/tags\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/posts?tags=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}