{"id":1125,"count":5,"description":"","link":"https:\/\/template01.zehannet.net\/ja\/tag\/sports-nets\/","name":"Sports Nets","slug":"sports-nets","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/tags\/1125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/posts?tags=1125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}