{"id":1020,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/ja\/tag\/interior-sports-facility-expense\/","name":"interior sports facility expense","slug":"interior-sports-facility-expense","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/tags\/1020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/ja\/wp-json\/wp\/v2\/posts?tags=1020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}