{"id":690,"count":2,"description":"","link":"https:\/\/template01.zehannet.net\/it\/tag\/moq-negotiation\/","name":"Negoziazione del MOQ","slug":"moq-negotiation","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/tags\/690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/posts?tags=690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}