{"id":1201,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/it\/tag\/heavy-duty-sports-netting\/","name":"heavy-duty sports netting","slug":"heavy-duty-sports-netting","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/tags\/1201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/posts?tags=1201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}