{"id":1431,"date":"2023-04-25T13:47:54","date_gmt":"2023-04-25T05:47:54","guid":{"rendered":"https:\/\/template01.zehannet.net\/?post_type=product&#038;p=1431"},"modified":"2023-04-25T13:47:54","modified_gmt":"2023-04-25T05:47:54","slug":"mini-portable-tennis-net-for-driveway-kids-soccer-tennis-net","status":"publish","type":"product","link":"https:\/\/template01.zehannet.net\/it\/product\/mini-portable-tennis-net-for-driveway-kids-soccer-tennis-net\/","title":{"rendered":"Mini rete da tennis portatile per vialetto bambini calcio rete da tennis"},"content":{"rendered":"<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li><span class=\"a-list-item\">Lunghezza della rete: 10 piedi\/ 18 piedi, altezza della rete: 33 pollici<\/span><\/li>\n<li><span class=\"a-list-item\">Adatti per giocare a tennis, calcio, pallavolo in piscina, pickleball<\/span><\/li>\n<li><span class=\"a-list-item\">Facile da installare e smontare<\/span><\/li>\n<li><span class=\"a-list-item\">10ft utilizzato per la rete da tennis, rete da calcio tennis, rete pickleball<\/span><\/li>\n<li><span class=\"a-list-item\">18ft utilizzato per la rete da tennis, rete da calcio tennis, rete da pickleball, rete da pallavolo in piscina<\/span><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Le reti e i sistemi di reti di altissima qualit\u00e0 di Fsports sono una soluzione economica del leader del settore delle reti e degli accessori per il tennis.<\/p>","protected":false},"featured_media":1445,"template":"","meta":{"_gspb_post_css":""},"product_brand":[],"product_cat":[33],"product_tag":[],"class_list":["post-1431","product","type-product","status-publish","has-post-thumbnail","product_cat-tennis-net","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product\/1431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/media\/1445"}],"wp:attachment":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/media?parent=1431"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_brand?post=1431"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_cat?post=1431"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_tag?post=1431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}