{"id":1196,"date":"2023-04-19T15:52:10","date_gmt":"2023-04-19T07:52:10","guid":{"rendered":"https:\/\/template01.zehannet.net\/?post_type=product&#038;p=1196"},"modified":"2023-04-19T15:58:03","modified_gmt":"2023-04-19T07:58:03","slug":"3-way-volleyball-net-beach-game-set-for-adults-and-kids","status":"publish","type":"product","link":"https:\/\/template01.zehannet.net\/it\/product\/3-way-volleyball-net-beach-game-set-for-adults-and-kids\/","title":{"rendered":"Set di 4 partite di pallavolo per adulti e bambini"},"content":{"rendered":"<p><strong>Dimensioni e peso<\/strong><\/p>\n<ul>\n<li>1. Dimensioni: 4*2,43*2,26m<br \/>\n2.Rete: 1,5\u201d rete PE con tessuto oxford 420D<br \/>\n3.Telaio: Ferro d'acciaio Dia 22*0,8 mm<br \/>\n4.Fibra di vetro: 7*3.0*33cm<br \/>\n5.borsa a tracolla: 420DPU<br \/>\n6.Dimensioni del cartone: Lx62,9xL18,4xD20,3cmIstruzioni per l'uso<\/li>\n<li>Pallavolo FSports: Rete da pallavolo a 3 vie completamente regolabile e gioco perfetto per tutte le occasioni. Indispensabile per feste, barbecue ed eventi, e regalo perfetto per chi si trova all'aperto, FSports \u00e8 un gioco attivo di quattro quadrati che incontra la pallavolo. Perfettamente dimensionato per quattro giocatori per turno, FSports offre a voi e alla vostra squadra un divertimento sicuro, semplice e a prova di bomba!<br \/>\nPERFETTA PER OGNI AVVENTURA: Costruita per durare e perfetta per la vostra prossima uscita, questa rete di alta qualit\u00e0 sar\u00e0 sicuramente un punto fermo del vostro divertimento estivo! Che siate in spiaggia, al parco o al lago, FSports \u00e8 il catalizzatore perfetto per il divertimento della famiglia e per una competizione amichevole!<br \/>\nINSTALLAZIONE FACILE E VELOCE: Caratterizzato da un design unico nel suo genere, tanto intuitivo quanto compatto, il montaggio e lo smontaggio sono un gioco da ragazzi! Godetevi il divertimento in pochi minuti e richiudete tutto nello zaino FSports di dimensioni perfette in altrettanto tempo, per essere pronti a scatenarvi verso la vostra prossima avventura!<br \/>\nPER GIOCATORI DI TUTTE LE ET\u00c0: Regalo perfetto! Sia i pi\u00f9 piccoli che gli adulti ameranno FSports! Con tutto ci\u00f2 che \u00e8 incluso per modificare l'altezza della rete, insieme alle regole e agli obiettivi del gioco, semplici e facili da capire, tutta la famiglia pu\u00f2 partecipare al divertimento.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Rete da pallavolo a 3 vie con zaino per il trasporto e palla - Set da gioco di pallavolo a 3 piazze per adulti e bambini - Gioco all'aperto di rapido montaggio - Giochi da cortile<\/p>","protected":false},"featured_media":1177,"template":"","meta":{"_gspb_post_css":""},"product_brand":[],"product_cat":[31],"product_tag":[],"class_list":["post-1196","product","type-product","status-publish","has-post-thumbnail","product_cat-volleyball-net","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product\/1196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/media\/1177"}],"wp:attachment":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/media?parent=1196"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_brand?post=1196"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_cat?post=1196"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_tag?post=1196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}