{"id":1042,"date":"2023-04-15T15:31:41","date_gmt":"2023-04-15T07:31:41","guid":{"rendered":"https:\/\/template01.zehannet.net\/?post_type=product&#038;p=1042"},"modified":"2023-04-15T17:12:21","modified_gmt":"2023-04-15T09:12:21","slug":"sport-nets-portable-soccer-goal-bow-frame-soccer-net-with-carry-bag","status":"publish","type":"product","link":"https:\/\/template01.zehannet.net\/it\/product\/sport-nets-portable-soccer-goal-bow-frame-soccer-net-with-carry-bag\/","title":{"rendered":"Reti sportive Rete da calcio portatile con telaio ad arco e borsa per il trasporto"},"content":{"rendered":"<p>1. Dimensioni: 3\u00d75\u2032, 4\u00d76\u2032, 4\u00d78\u2032, 4\u00d712\u2032, 4\u00d716\u2032, 5\u00d710\u2032, 6\u00d712\u2032, 7\u00d714\u2032, 6\u20196 \u201dx18\u20196\u201d, 7\u00d716\u2032, 7\u00d721\u2032, 8\u00d724\u2032.<br \/>\n2. Rete: Rete in poliestere senza nodi 5 veli 4\u201d, 8 veli 4\u201d, 22 veli 4\u201d.\u201d<br \/>\n3. Tubo in acciaio: \u03c625mmx25mm, \u03c630mmx30mm<br \/>\n4. Fibra di vetro: \u03c612,7 mm, \u03c614 mm, \u03c616 mm, \u03c619 mm.<\/p>\n<p>Include una porta da calcio rettangolare con telaio ad arco (il telaio \u00e8 piegato per garantire la distanza dal terreno) con picchetti in acciaio per il terreno e una borsa per il trasporto con cerniera e cinghia.<br \/>\nDisponibile in diverse misure, \u00e8 adatto a tutte le et\u00e0, bambini, ragazzi, giovani, adulti o allenatori. Da utilizzare per campionati, scuole, tornei o allenamenti in solitaria.<br \/>\nLa rete per porte da calcio di Fsports pu\u00f2 facilmente utilizzare pesi di stabilit\u00e0 per pavimentazioni interne, palestre, impianti di calcio al coperto e altro ancora.<br \/>\nLe reti da calcio per il cortile sono dotate di picchetti metallici per garantire la stabilit\u00e0 del gioco su erba, sabbia o manto erboso.<br \/>\nRealizzata con la nostra resistente rete in polietilene annodata per tutte le stagioni e resistente all'usura e con un telaio in acciaio rivestito di nero con aste flessibili in fibra di vetro per impieghi gravosi.<br \/>\nPorte da calcio per il cortile, le partite di recupero, le esercitazioni, il parco, la casa, il campo o la spiaggia. Da portare ovunque, portatile e leggera<br \/>\nFacile da montare e smontare senza bisogno di attrezzi. Il telaio di base in metallo resistente si estende facilmente per un rapido allenamento di calcio o per giocare in movimento. Ideale per qualsiasi tipo di terreno, grazie alla struttura di base progettata per essere angolata in modo da lasciare spazio al terreno.<br \/>\nLe porte da calcio portatili Fsports si inseriscono facilmente nella nostra borsa da trasporto con cerniera rinforzata e maniglia. Include una resistente rete in velcro costruita per durare nel tempo.<br \/>\nDa riporre in garage, a casa, in un capannone o da portare ovunque in modo semplice e veloce. Design compatto e portatile per adattarsi a qualsiasi bagagliaio o sedile posteriore dell'auto.<br \/>\nUtilizza palloni da calcio regolamentari di dimensioni 3, 4 o 5. Portate il vostro gioco a un livello superiore con la nostra attrezzatura da calcio pieghevole da viaggio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Rete da calcio portatile per cortile, rete sportiva Rete da calcio sportiva portatile istantanea, per tutte le et\u00e0 e livello di abilit\u00e0 e ovunque, per allenamento e prove, 1 rete + 1 borsa per il trasporto, disponibile in varie dimensioni<\/p>","protected":false},"featured_media":1047,"template":"","meta":{"_gspb_post_css":""},"product_brand":[],"product_cat":[29],"product_tag":[],"class_list":["post-1042","product","type-product","status-publish","has-post-thumbnail","product_cat-soccer-goal","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/media\/1047"}],"wp:attachment":[{"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_brand?post=1042"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_cat?post=1042"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/template01.zehannet.net\/it\/wp-json\/wp\/v2\/product_tag?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}