{"id":1112,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/fr\/tag\/uv-stabilized-sports-netting\/","name":"UV-stabilized sports netting","slug":"uv-stabilized-sports-netting","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/tags\/1112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/posts?tags=1112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}