{"id":1090,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/fr\/tag\/sports-netting-procurement\/","name":"sports netting procurement","slug":"sports-netting-procurement","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/tags\/1090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/fr\/wp-json\/wp\/v2\/posts?tags=1090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}