{"id":999,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/es\/tag\/sports-facility-design\/","name":"sports facility design","slug":"sports-facility-design","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/tags\/999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/posts?tags=999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}