{"id":1451,"date":"2023-04-25T14:34:37","date_gmt":"2023-04-25T06:34:37","guid":{"rendered":"https:\/\/template01.zehannet.net\/?post_type=product&#038;p=1451"},"modified":"2023-04-25T14:37:26","modified_gmt":"2023-04-25T06:37:26","slug":"standard-tennis-net-with-winch-cable-42-plastic-coated-vinyl-netting","status":"publish","type":"product","link":"https:\/\/template01.zehannet.net\/es\/product\/standard-tennis-net-with-winch-cable-42-plastic-coated-vinyl-netting\/","title":{"rendered":"Red de tenis est\u00e1ndar con cable de cabrestante 42\u2033 Red recubierta de pl\u00e1stico y vinilo"},"content":{"rendered":"<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li><span class=\"a-list-item\">Red de tenis est\u00e1ndar de 42\u2032 de longitud y 3,5\u2032 de altura.<\/span><\/li>\n<li><span class=\"a-list-item\">Red de poli\u00e9ster trenzado de 4 mm de alta calidad<\/span><\/li>\n<li><span class=\"a-list-item\">Cable de acero recubierto de vinilo de 6 mm<\/span><\/li>\n<li><span class=\"a-list-item\">Ideal para su uso en clubes, escuelas, gimnasios y otros lugares con una pista de tenis comunitaria.<\/span><\/li>\n<li><span class=\"a-list-item\">Bolsa de transporte port\u00e1til incluida<\/span><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n:<br \/>\nJuegue al tenis en la playa, en la entrada de casa, en el patio trasero y en cualquier zona llana.<br \/>\nMuy r\u00e1pida de montar y guardar, plegable, ligera y f\u00e1cil de transportar.<br \/>\nIdeal para fiestas, acampadas y vacaciones familiares. Apenas ocupa espacio en el maletero del coche.<br \/>\nFabricado con red resistente para evitar desgarros y garantizar su durabilidad. Con una construcci\u00f3n robusta, utilizar en interiores y al aire libre sin preocupaciones.<br \/>\n\u00a1Haga que sus hijos salgan y se muevan! Esta red port\u00e1til es perfecta para el juego ocasional y el entrenamiento deportivo de adultos y ni\u00f1os.<\/p>","protected":false},"featured_media":1436,"template":"","meta":{"_gspb_post_css":""},"product_brand":[],"product_cat":[33],"product_tag":[],"class_list":["post-1451","product","type-product","status-publish","has-post-thumbnail","product_cat-tennis-net","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/product\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/media\/1436"}],"wp:attachment":[{"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/media?parent=1451"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/product_brand?post=1451"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/product_cat?post=1451"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/template01.zehannet.net\/es\/wp-json\/wp\/v2\/product_tag?post=1451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}