{"id":1133,"count":1,"description":"","link":"https:\/\/template01.zehannet.net\/de\/tag\/sports-net-design-support\/","name":"sports net design support","slug":"sports-net-design-support","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/template01.zehannet.net\/de\/wp-json\/wp\/v2\/tags\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/template01.zehannet.net\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/template01.zehannet.net\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/template01.zehannet.net\/de\/wp-json\/wp\/v2\/posts?tags=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}